{"id":4726,"date":"2023-02-16T13:01:22","date_gmt":"2023-02-16T13:01:22","guid":{"rendered":"https:\/\/arcadiareptile.com\/leitfaden\/"},"modified":"2023-09-19T14:04:12","modified_gmt":"2023-09-19T14:04:12","slug":"leitfaden","status":"publish","type":"page","link":"https:\/\/arcadiareptile.com\/de\/leitfaden\/","title":{"rendered":"Leitfaden"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4726\" class=\"elementor elementor-4726 elementor-222\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5deceb2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5deceb2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53b54c40\" data-id=\"53b54c40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e94edf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e94edf8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-031db02\" data-id=\"031db02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45bef14 elementor-widget elementor-widget-heading\" data-id=\"45bef14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Interaktiver UV-Index<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a81623d elementor-widget elementor-widget-heading\" data-id=\"a81623d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Handbuch Beleuchtung <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bd2910c elementor-hidden-mobile elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1bd2910c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1.3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6852c2 elementor-widget elementor-widget-text-editor\" data-id=\"f6852c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Geben Sie einfach Ihre Tierart ein und Sie erhalten den optimalen UV-Index f\u00fcr Ihre Tierart innerhalb der H\u00f6he des Geheges.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebf05a6 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"ebf05a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser Ziel ist es, jeder Tierart die Energie zu geben, an die sie angepasst ist, und zwar auf sichere und angemessene Weise. Auf diese Weise k\u00f6nnen wir gesunde, aktive Reptilien halten und sicherstellen, dass vermeidbare Krankheiten weniger wahrscheinlich auftreten.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1ed4824 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ed4824\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5423300\" data-id=\"5423300\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9292236 elementor-widget elementor-widget-spacer\" data-id=\"9292236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c62fd0f elementor-widget elementor-widget-html\" data-id=\"c62fd0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t <input type=\"text\" style=\"border: 2px solid #46E4E3;\" id=\"searchInput\" placeholder=\"Spezies\" autocomplete=\"off\">\n  <ul id=\"resultsContainer\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-065856b elementor-widget elementor-widget-spacer\" data-id=\"065856b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c314fe7 elementor-widget elementor-widget-text-editor\" data-id=\"c314fe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Ihr Tier nicht in unserem Suchfeld erscheint, senden Sie uns bitte den Namen der Tierart:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4455805 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"4455805\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Weiter&quot;,&quot;step_previous_label&quot;:&quot;Vorherige&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Neue Form\" aria-label=\"Neue Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"4726\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"4455805\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Leitfaden - Arcadia Reptile\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"4726\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tName\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Arten\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tE-mail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha elementor-field-group elementor-column elementor-field-group-field_0a92b07 elementor-col-100\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_0a92b07\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcGbxgoAAAAAMzuMVyqF1_CzGFsq8PvlZcBQcI8\" data-type=\"v2_checkbox\" data-theme=\"dark\" data-size=\"normal\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-lg\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3983314 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3983314\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc86636\" data-id=\"bc86636\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-487c257 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"487c257\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d3cf5d4\" data-id=\"d3cf5d4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b3e5ef elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9b3e5ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1.3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef6f4d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef6f4d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12bd4220\" data-id=\"12bd4220\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4855a101 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4855a101\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6a5b4551\" data-id=\"6a5b4551\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56c3ea89 elementor-widget elementor-widget-text-editor\" data-id=\"56c3ea89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"mt20 din exexlg\">Der Arcadia Reptile Light Guide ist ein Hilfsmittel, das es Tierhaltern erm\u00f6glicht, eine sachkundige Wahl der Beleuchtung f\u00fcr ihre Reptilien, Amphibien oder Wirbellosen zu treffen.<\/p>\n<p class=\"mt20\">In der Vergangenheit lautete der Ratschlag f\u00fcr Reptilien einfach, eine 5%ige UVB-Lampe f\u00fcr Waldtiere und eine 10%ige Lampe f\u00fcr W\u00fcstentiere zu kaufen. Es wurde nicht wirklich \u00fcber die einzigartigen Anpassungen der Arten und ihr Sonnenverhalten oder den Abstand zwischen der Lampe und dem Tier im Wohnbereich nachgedacht. Nur wenige haben sich Gedanken dar\u00fcber gemacht, wie man den UVI-Wert in der freien Natur nachbilden k\u00f6nnte.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2da2a4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2da2a4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5837757\" data-id=\"5837757\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f352da1 elementor-widget elementor-widget-heading\" data-id=\"f352da1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Zeit f\u00fcr eine Ver\u00e4nderung<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5b96ab elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d5b96ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1.3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f38f641 elementor-widget elementor-widget-text-editor\" data-id=\"f38f641\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"mt10\">Hier bei Arcadia Reptile haben wir beschlossen, die Beleuchtungsempfehlungen neu zu schreiben. Dabei haben wir uns auf die Wissenschaft gest\u00fctzt und nicht auf Verallgemeinerungen. Jetzt k\u00f6nnen die Tierhalter die ver\u00f6ffentlichten Werte der Lampen verwenden, um die UV-Werte (UVI) der Arten in freier Wildbahn nachzubilden. Wir untersuchten die UVI-Werte in freier Wildbahn in der Umgebung h\u00e4ufiger Arten, und wir untersuchten die Lebensr\u00e4ume beliebter Arten, um zu verstehen, wie jede Art die Sonnenenergie nutzt. Wir untersuchten die Hautdicke der einzelnen Arten und \u00fcberpr\u00fcften diese mit der Tetrachromie (der F\u00e4higkeit der Reptilien, UV-Licht zu sehen), um herauszufinden, wie viel Licht den einzelnen Arten in freier Wildbahn zur Verf\u00fcgung stehen w\u00fcrde. Wir entdeckten auch, was heute als Blatt- oder Felsstreulicht bekannt ist. Mit diesen Begriffen wird das Licht bezeichnet, das vom Bl\u00e4tterdach des Waldes nach unten f\u00e4llt oder durch L\u00f6cher und Spalten in Felsen dringt. Dies bedeutet, dass die Arten, die traditionell als Arten mit geringem Lichtbedarf eingestuft wurden, nun in der Lage sind, UV-Licht effizient zu nutzen.<\/p>\n<p class=\"mt20 mb30\">Zum Beispiel werden Goldmantelfr\u00f6sche traditionell mit einer 2 %igen T8-UV-R\u00f6hre als Standard gehalten. Aus Berichten \u00fcber ihr Verhalten in der freien Natur geht jedoch hervor, dass sie h\u00e4ufig Sonnenflecken nutzen, die durch Unterbrechungen im Bl\u00e4tterdach des Waldes entstehen und einen recht hohen W\u00e4rme- und UV-Anteil aufweisen. Daher w\u00fcrden wir jetzt vorschlagen, eine Lampe mit h\u00f6herer Leistung in Verbindung mit einer dichten Bepflanzung zu verwenden, um diesen Effekt des Streiflichts zu erm\u00f6glichen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-499a3f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"499a3f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6fd8b6e\" data-id=\"6fd8b6e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77addb4 elementor-widget elementor-widget-heading\" data-id=\"77addb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Die Beleuchtungsanleitung<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5484a5 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a5484a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 20 16&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1.3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cg transform=&#039;translate(-12.000000, 0)&#039;%3E%3Cpath d=&#039;M28,0L10,18&#039;\/%3E%3Cpath d=&#039;M18,0L0,18&#039;\/%3E%3Cpath d=&#039;M48,0L30,18&#039;\/%3E%3Cpath d=&#039;M38,0L20,18&#039;\/%3E%3C\/g%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e45242 elementor-widget elementor-widget-text-editor\" data-id=\"4e45242\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"mt20\">Es ist wichtig, dass Ihr Reptil die richtige Menge an UV-Licht erh\u00e4lt. Dieser Beleuchtungsleitfaden zeigt Ihnen, wie Sie Ihr UV-System richtig einrichten. Wir haben die UVI-Messungen auf unabh\u00e4ngige Messungen unserer UVB-Leuchtstofflampen mit einem SolarMeter 6.5 gest\u00fctzt. Damit wird der Teil des Lichts gemessen, der von den Tieren f\u00fcr die Vitamin D3-Produktion genutzt wird.<\/p>\n<p class=\"mt20\">In diesem Beleuchtungsleitfaden wird f\u00fcr jede Tierart ein empfohlener Ultraviolett-Index (UVI) f\u00fcr verschiedene Entfernungen von der Lampe zum Kopf des Tieres angegeben. Um diese Werte zu ermitteln, haben wir den verf\u00fcgbaren Index des Heimatgebiets (das geografische Wildgebiet der Art) anhand der Daten von Wetterstationen auf der ganzen Welt um 11 Uhr morgens untersucht. Anschlie\u00dfend haben wir diesen Index reduziert, um die Bew\u00f6lkung zu ber\u00fccksichtigen, und ihn in Abh\u00e4ngigkeit von der Position des Tieres in der Umgebung und seinem Sonnenverhalten, d. h. ob es sich um einen Schattenbewohner oder einen Sonnenanbeter handelt, weiter reduziert. Wir geben dann eine Empfehlung f\u00fcr die Art und St\u00e4rke der Lampe, um diesen UVI zu erreichen. Auf diese Weise k\u00f6nnen Sie ein System einrichten, bei dem das Tier selbst entscheiden kann, ob es sich dem Licht aussetzen m\u00f6chte oder ob es sich der direkten Sonneneinstrahlung entziehen m\u00f6chte. Dies ist die Grundlage der Licht- und Schattenmethode.<\/p>\n<p class=\"mt20\">Leopardgeckos zum Beispiel stammen aus Afghanistan, wo der UVI-Wert oft 6 erreicht. Leopardgeckos sind jedoch d\u00e4mmerungsaktiv, d. h. sie sind haupts\u00e4chlich bei geringer Sonneneinstrahlung aktiv. Au\u00dferdem sonnen sie sich normalerweise, indem sie nur Teile ihres K\u00f6rpers entbl\u00f6\u00dfen. Es hat sich auch gezeigt, dass der Leopardgecko eine Haut entwickelt hat, die UV-B-Strahlen w\u00e4hrend dieser Zeit besonders gut absorbiert. Daher m\u00fcssen wir darauf achten, dass sie nicht \u00fcberbelichtet werden. Wir empfehlen einen UVI-Wert von 2 bis 3 f\u00fcr den gesamten Sonnenbereich und bis zu 0 am k\u00fchlen Ende.<\/p>\n<p class=\"mt20\">Alle Empfehlungen basieren auf der Verwendung einer Lampe mit einem geeigneten Reflektor, der an der Innenseite eines Haltungsbereichs angebracht ist. Wir haben rund 140 Reptilien-, Amphibien- und Wirbellosenarten abgedeckt und werden die Liste im Laufe der Zeit aktualisieren und erg\u00e4nzen.<\/p>\n<p class=\"mt20 mb50\">Bitte w\u00e4hlen Sie Ihre Tierart aus dem obigen Dropdown-Men\u00fc aus. Dort finden Sie die empfohlene UV-Lampe f\u00fcr den Abstand zwischen Ihrer Liegezone und Ihren Lampen bzw. den Abstand zwischen der Lampe und dem Kopf\/der Oberseite des Panzers Ihres Tieres.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Interaktiver UV-Index Handbuch Beleuchtung Geben Sie einfach Ihre Tierart ein und Sie erhalten den optimalen UV-Index f\u00fcr Ihre Tierart innerhalb der H\u00f6he des Geheges. Unser Ziel ist es, jeder Tierart die Energie zu geben, an die sie angepasst ist, und zwar auf sichere und angemessene Weise. Auf diese Weise k\u00f6nnen wir gesunde, aktive Reptilien halten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-4726","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leitfaden - Arcadia Reptile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arcadiareptile.com\/de\/leitfaden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leitfaden - Arcadia Reptile\" \/>\n<meta property=\"og:description\" content=\"Interaktiver UV-Index Handbuch Beleuchtung Geben Sie einfach Ihre Tierart ein und Sie erhalten den optimalen UV-Index f\u00fcr Ihre Tierart innerhalb der H\u00f6he des Geheges. Unser Ziel ist es, jeder Tierart die Energie zu geben, an die sie angepasst ist, und zwar auf sichere und angemessene Weise. Auf diese Weise k\u00f6nnen wir gesunde, aktive Reptilien halten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arcadiareptile.com\/de\/leitfaden\/\" \/>\n<meta property=\"og:site_name\" content=\"Arcadia Reptile\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-19T14:04:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/leitfaden\\\/\",\"url\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/leitfaden\\\/\",\"name\":\"Leitfaden - Arcadia Reptile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/#website\"},\"datePublished\":\"2023-02-16T13:01:22+00:00\",\"dateModified\":\"2023-09-19T14:04:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/leitfaden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/leitfaden\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/leitfaden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leitfaden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/\",\"name\":\"Arcadia Reptile\",\"description\":\"Arcadia Reptile\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arcadiareptile.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leitfaden - Arcadia Reptile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arcadiareptile.com\/de\/leitfaden\/","og_locale":"de_DE","og_type":"article","og_title":"Leitfaden - Arcadia Reptile","og_description":"Interaktiver UV-Index Handbuch Beleuchtung Geben Sie einfach Ihre Tierart ein und Sie erhalten den optimalen UV-Index f\u00fcr Ihre Tierart innerhalb der H\u00f6he des Geheges. Unser Ziel ist es, jeder Tierart die Energie zu geben, an die sie angepasst ist, und zwar auf sichere und angemessene Weise. Auf diese Weise k\u00f6nnen wir gesunde, aktive Reptilien halten [&hellip;]","og_url":"https:\/\/arcadiareptile.com\/de\/leitfaden\/","og_site_name":"Arcadia Reptile","article_modified_time":"2023-09-19T14:04:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arcadiareptile.com\/de\/leitfaden\/","url":"https:\/\/arcadiareptile.com\/de\/leitfaden\/","name":"Leitfaden - Arcadia Reptile","isPartOf":{"@id":"https:\/\/arcadiareptile.com\/de\/#website"},"datePublished":"2023-02-16T13:01:22+00:00","dateModified":"2023-09-19T14:04:12+00:00","breadcrumb":{"@id":"https:\/\/arcadiareptile.com\/de\/leitfaden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arcadiareptile.com\/de\/leitfaden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arcadiareptile.com\/de\/leitfaden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arcadiareptile.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Leitfaden"}]},{"@type":"WebSite","@id":"https:\/\/arcadiareptile.com\/de\/#website","url":"https:\/\/arcadiareptile.com\/de\/","name":"Arcadia Reptile","description":"Arcadia Reptile","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arcadiareptile.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/arcadiareptile.com\/de\/wp-json\/wp\/v2\/pages\/4726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcadiareptile.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arcadiareptile.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arcadiareptile.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arcadiareptile.com\/de\/wp-json\/wp\/v2\/comments?post=4726"}],"version-history":[{"count":0,"href":"https:\/\/arcadiareptile.com\/de\/wp-json\/wp\/v2\/pages\/4726\/revisions"}],"wp:attachment":[{"href":"https:\/\/arcadiareptile.com\/de\/wp-json\/wp\/v2\/media?parent=4726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}